{"id":9501,"date":"2022-08-09T10:05:54","date_gmt":"2022-08-09T17:05:54","guid":{"rendered":"https:\/\/chs-ca.org\/sin-categorizar\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\/"},"modified":"2023-06-14T10:38:23","modified_gmt":"2023-06-14T17:38:23","slug":"ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas","status":"publish","type":"post","link":"https:\/\/chs-ca.org\/es\/chs-blog\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\/","title":{"rendered":"Ago 2022 &#8211; El comportamiento como comunicaci\u00f3n: C\u00f3mo entender las crisis y las rabietas"},"content":{"rendered":"<p>Las rabietas y las crisis se suelen utilizar indistintamente para describir un comportamiento caracterizado por la expresi\u00f3n de intensos estallidos de emoci\u00f3n. Todos los comportamientos tienen una finalidad: comunicar. Entonces, \u00bfcu\u00e1l es la diferencia entre una rabieta y una crisis?  <\/p>\n<p>A continuaci\u00f3n, analizaremos las diferencias, las causas y las estrategias para responder a ambas.<\/p>\n<p><span style=\"text-decoration: underline;\">\u00bfQu\u00e9 son las rabietas?<\/span> <br \/>A medida que los ni\u00f1os se vuelven m\u00e1s curiosos e independientes en el mundo que les rodea, pueden probar cosas nuevas para las que a\u00fan no est\u00e1n preparados emocional o f\u00edsicamente. Como resultado, esto que puede causar frustraci\u00f3n al ni\u00f1o. Las rabietas se producen cuando el ni\u00f1o intenta comunicar sus necesidades y estas no son satisfechas. Esto se considera una parte normal del desarrollo del ni\u00f1o. Las rabietas suelen comenzar durante el primer a\u00f1o de vida del ni\u00f1o y <a href=\"https:\/\/healthychildren.org\/english\/ages-stages\/pages\/default.aspx\" target=\"_blank\" rel=\"noopener\">habitualmente contin\u00faan hasta los cuatro a\u00f1os de edad<\/a>. Normalmente disminuyen en frecuencia y magnitud a medida que aumentan las habilidades comunicativas del ni\u00f1o.    <\/p>\n<p>Las rabietas ocurren cuando un ni\u00f1o expresa un arrebato de irritabilidad, como la ira o la frustraci\u00f3n, y carece de las habilidades de afrontamiento para manejar las emociones fuertes o las decepciones.<\/p>\n<p><a href=\"https:\/\/www.oxfordlearnersdictionaries.com\/us\/definition\/american_english\/tantrum\" target=\"_blank\" rel=\"noopener\">Las rabietas<\/a> pueden ser f\u00edsicas o verbales. Algunos signos de estos comportamientos van desde gritos, gimoteos, llantos o agresiones f\u00edsicas como morder, dar patadas, tirar cosas, aguantar la respiraci\u00f3n o tirarse al suelo. <\/p>\n<p><span style=\"text-decoration: underline;\">\u00bfQu\u00e9 causa las rabietas?<br \/><\/span> Entre las causas de las <a href=\"https:\/\/kidshealth.org\/en\/parents\/temper.html\" target=\"_blank\" rel=\"noopener\">rabietas<\/a> se incluyen:<\/p>\n<ul>\n<li>Estar cansado o hambriento<\/li>\n<li>Buscar atenci\u00f3n<\/li>\n<li>Sentirse molesto, preocupado o frustrado<\/li>\n<li>Incapacidad o dificultad para expresar lo que quiere o siente<\/li>\n<li>Que le quiten algo o no le den lo que quiere<\/li>\n<\/ul>\n<p><span style=\"text-decoration: underline;\">C\u00f3mo responder a una rabieta<\/span> <br \/><a href=\"https:\/\/sesamestreetincommunities.org\/topics\/tantrums\/\" target=\"_blank\" rel=\"noopener\">Recuerde que debe mantener la calma<\/a>. Los ni\u00f1os aprenden a desenvolverse y a expresar sus deseos y necesidades. Un adulto que modele c\u00f3mo manejar una determinada situaci\u00f3n puede ayudar a los ni\u00f1os a aprender estrategias de comunicaci\u00f3n positivas.  <\/p>\n<ul>\n<li>Reconozca las emociones de su hijo y proporci\u00f3nele un lenguaje que le ayude a etiquetar esas emociones. Por ejemplo: \u00abVeo que est\u00e1s molesto porque es la hora de la limpieza. Yo tambi\u00e9n me enfado cuando tengo que dejar de hacer algo divertido\u00bb. <\/li>\n<li>Si es seguro hacerlo, ignore la rabieta hasta que est\u00e9 m\u00e1s calmado y dispuesto a hablar.<\/li>\n<li>Mant\u00e9ngalo seguro y a la vista y retire cualquier objeto peligroso que est\u00e9 al alcance de su hijo.<\/li>\n<li>No ceda a la rabieta ya que eso solo reforzar\u00e1 el comportamiento.<\/li>\n<li>Evite las luchas de poder. Intente llegar a un acuerdo y ayude al ni\u00f1o a completar la tarea necesaria. Por ejemplo, \u00abEs la hora de la limpieza. \u00bfPuedo ayudarte a recoger un juguete y t\u00fa me ayudas a recoger otro juguete?\u00bb  <\/li>\n<\/ul>\n<p><span style=\"text-decoration: underline;\">C\u00f3mo apoyar a su hijo durante las rabietas<\/span> <br \/>Las rabietas forman parte del proceso normal de desarrollo del ni\u00f1o. A continuaci\u00f3n se indican algunos pasos para apoyar a su hijo y ayudar a prevenir o disminuir las rabietas: <\/p>\n<ul>\n<li>Reconocer los l\u00edmites de su hijo: lleve un registro de cu\u00e1ndo se produce el comportamiento y reflexione sobre lo que el ni\u00f1o estaba haciendo antes o despu\u00e9s de la rabieta. Reflexione sobre el entorno del ni\u00f1o cuando se produjo el comportamiento. \u00bfHay algo que pueda cambiar para evitar la rabieta?  <\/li>\n<li>Sea flexible: Proporcione a su hijo cierto control sobre su d\u00eda. Por ejemplo, puede asignarle tareas apropiadas para su desarrollo, como dar de comer a una mascota de la familia o hacer que prepare o elija sus tentempi\u00e9s favoritos para el d\u00eda. <\/li>\n<li>Proporcione estructura y coherencia con un horario predecible. Si va a haber un cambio de horario, avise a su hijo con antelaci\u00f3n. Por ejemplo: \u00abEst\u00e1 lloviendo, as\u00ed que hoy no podremos ir al parque como hab\u00edamos planeado. Pensemos en algo divertido que podamos hacer en casa\u00bb.  <\/li>\n<li>Prepare las transiciones con antelaci\u00f3n, ya que esto da la oportunidad a los ni\u00f1os de estar preparados para un cambio de entorno o de rutina. Por ejemplo, \u00abYa casi es hora de limpiar. \u00bfQuieres que te ayude a guardar lo que est\u00e1s haciendo en un lugar seguro para que puedas seguir haci\u00e9ndolo m\u00e1s tarde?\u00bb <\/li>\n<li>Refuerce el comportamiento positivo. Por ejemplo, \u00abGracias por decirme que est\u00e1s frustrado. \u00bfC\u00f3mo podemos ayudar a resolver este problema juntos?\u00bb <\/li>\n<li>Cree un <a href=\"https:\/\/yogakids.com\/yoga-tools-for-temper-tantrums\/\" target=\"_blank\" rel=\"noopener\">kit de herramientas<\/a> con su hijo que le ayude a tranquilizarse. El kit de herramientas puede incluir estrategias de respiraci\u00f3n profunda o de expresi\u00f3n de emociones, un art\u00edculo de consuelo favorito, m\u00fasica relajante o papel y l\u00e1pices de colores para dibujar.<\/li>\n<\/ul>\n<p><span style=\"text-decoration: underline;\">\u00bfQu\u00e9 son las crisis?<\/span><br \/><a href=\"https:\/\/parents.actionforchildren.org.uk\/behaviour\/challenging-behaviour\/what-can-i-do-if-my-child-has-a-meltdown\/\" target=\"_blank\" rel=\"noopener\">Las crisis<\/a> son una reacci\u00f3n al sentirse sobreestimulado o abrumado y tienden a ser de mayor magnitud (m\u00e1s expresivas, de mayor duraci\u00f3n, de acci\u00f3n m\u00e1s extrema) que una rabieta. Algunas reacciones pueden consistir en gritar, huir, aislarse o retraerse. <\/p>\n<p><span style=\"text-decoration: underline;\">\u00bfQu\u00e9 puede provocar una crisis?<\/span> <br \/>Algunas causas de las crisis son:<\/p>\n<ul>\n<li>Sobrecarga sensorial que incluye: im\u00e1genes, sonidos, sabores o texturas<\/li>\n<li>Cambios repentinos en las rutinas diarias<\/li>\n<li>No ser capaz de comunicar sus necesidades<\/li>\n<li>Intensa frustraci\u00f3n<\/li>\n<\/ul>\n<p><span style=\"text-decoration: underline;\">C\u00f3mo responder a las crisis<\/span> <br \/>Cuando un ni\u00f1o tiene una crisis, es importante sacarlo de la situaci\u00f3n de sobrecarga sensorial a un entorno m\u00e1s tranquilo. Los ni\u00f1os pueden necesitar m\u00e1s tiempo para calmarse y procesar lo que ocurre a su alrededor que cuando experimentan una rabieta. <\/p>\n<p><span style=\"text-decoration: underline;\">C\u00f3mo apoyar a su hijo durante las crisis<\/span><\/p>\n<ul>\n<li>Familiar\u00edcese con los factores desencadenantes de su hijo y busque patrones en su comportamiento<\/li>\n<li>Sea paciente y mantenga la calma<\/li>\n<li>Est\u00e9 atento y f\u00edjese en cuando una crisis puede ir en aumento<\/li>\n<li>Proporcione estructura y coherencia con un horario predecible<\/li>\n<li>Valide y etiquete los sentimientos de su hijo<\/li>\n<li>Cree un kit de herramientas con su hijo que le ayude a tranquilizarse. El kit de herramientas puede personalizarse para reducir o eliminar los desencadenantes. Por ejemplo, unas gafas de sol oscuras pueden ayudar a calmar la sensibilidad a la luz, y un par de auriculares con cancelaci\u00f3n de ruido o unos tapones para los o\u00eddos (que sean seguros para ni\u00f1os) pueden minimizar los sonidos fuertes  <\/li>\n<li>Comparta los factores desencadenantes y las estrategias de afrontamiento de su hijo con otros miembros de la familia, cuidadores o profesores que pasen tiempo con su hijo<\/li>\n<\/ul>\n<p><span style=\"text-decoration: underline;\">Cu\u00e1ndo consultar al pediatra<\/span> <br \/>Si su hijo tiene rabietas o crisis nerviosas m\u00e1s all\u00e1 de los cuatro a\u00f1os, puede haber otras posibles causas subyacentes, y es importante consultar con su pediatra.<\/p>\n<p>Es normal que se sienta frustrado y que necesite consejo o apoyo sobre c\u00f3mo manejar las rabietas o las crisis de forma segura. A continuaci\u00f3n encontrar\u00e1 una serie de recursos para ayudar a las familias. <\/p>\n<p><span style=\"text-decoration: underline;\">Referencias y recursos:<\/span> <br \/><a href=\"https:\/\/healthychildren.org\/english\/ages-stages\/pages\/default.aspx\" target=\"_blank\" rel=\"noopener\">https:\/\/healthychildren.org\/english\/ages-stages\/pages\/default.aspx<\/a> <br \/><a href=\"https:\/\/kidshealth.org\/en\/parents\/tantrums.html\" target=\"_blank\" rel=\"noopener\">https:\/\/kidshealth.org\/en\/parents\/tantrums.html<\/a> <br \/><a href=\"https:\/\/kidshealth.org\/en\/parents\/temper.html?ref=search\" target=\"_blank\" rel=\"noopener\">https:\/\/kidshealth.org\/en\/parents\/temper.html?ref=search<\/a> <br \/><a href=\"https:\/\/www.understood.org\/en\/articles\/taming-tantrums-vs-managing-meltdowns\" target=\"_blank\" rel=\"noopener\">https:\/\/www.understood.org\/en\/articles\/taming-tantrums-vs-managing-meltdowns<\/a> <br \/><a href=\"https:\/\/www.webmd.com\/parenting\/video\/video-fit-coping-with-meltdowns\" target=\"_blank\" rel=\"noopener\">https:\/\/www.webmd.com\/parenting\/video\/video-fit-coping-with-meltdowns<\/a> <br \/><a href=\"https:\/\/www.webmd.com\/parenting\/guide\/preventing-temper-tantrums-in-children\" target=\"_blank\" rel=\"noopener\">https:\/\/www.webmd.com\/parenting\/guide\/preventing-temper-tantrums-in-children<\/a> <br \/><a href=\"https:\/\/www.stanfordchildrens.org\/en\/topic\/default?id=temper-tantrums-90-P02295\" target=\"_blank\" rel=\"noopener\">https:\/\/www.stanfordchildrens.org\/en\/topic\/default?id=temper-tantrums-90-P02295<\/a> <br \/><a href=\"https:\/\/sesamestreetincommunities.org\/topics\/tantrums\/\" target=\"_blank\" rel=\"noopener\">https:\/\/sesamestreetincommunities.org\/topics\/tantrums\/<\/a><br \/><a href=\"https:\/\/childmind.org\/article\/why-do-kids-have-tantrums-and-meltdowns\/\" target=\"_blank\" rel=\"noopener\">https:\/\/childmind.org\/article\/why-do-kids-have-tantrums-and-meltdowns\/<\/a><\/p><\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las rabietas y las crisis se suelen utilizar indistintamente para describir un comportamiento caracterizado<\/p>\n","protected":false},"author":4,"featured_media":8563,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","inline_featured_image":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[71,401],"tags":[155,422,423,424,426],"class_list":["post-9501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chs-blog","category-boletines-y-anuncios","tag-child-care-provider-resources","tag-ingles","tag-recursos-familiares","tag-recursos-para-proveedores-de-cuidado-infantil","tag-salud-mental"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ago 2022 - El comportamiento como comunicaci\u00f3n: C\u00f3mo entender las crisis y las rabietas - Children&#039;s Home Society of California<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chs-ca.org\/es\/chs-blog\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ago 2022 - El comportamiento como comunicaci\u00f3n: C\u00f3mo entender las crisis y las rabietas\" \/>\n<meta property=\"og:description\" content=\"Las rabietas y las crisis se suelen utilizar indistintamente para describir un comportamiento caracterizado\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chs-ca.org\/es\/chs-blog\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\/\" \/>\n<meta property=\"og:site_name\" content=\"Children&#039;s Home Society of California\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-09T17:05:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-14T17:38:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chs-ca.org\/wp-content\/uploads\/2022\/08\/ryan-franco-XECZHb6NoFo-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joanna Carlos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joanna Carlos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/chs-ca.org\\\/es\\\/chs-blog\\\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chs-ca.org\\\/es\\\/chs-blog\\\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\\\/\"},\"author\":{\"name\":\"Joanna Carlos\",\"@id\":\"https:\\\/\\\/chs-ca.org\\\/es\\\/#\\\/schema\\\/person\\\/41af37a0daa9fc962be2179a4207fed6\"},\"headline\":\"Ago 2022 &#8211; El comportamiento como comunicaci\u00f3n: C\u00f3mo entender las crisis y las rabietas\",\"datePublished\":\"2022-08-09T17:05:54+00:00\",\"dateModified\":\"2023-06-14T17:38:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/chs-ca.org\\\/es\\\/chs-blog\\\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\\\/\"},\"wordCount\":1241,\"publisher\":{\"@id\":\"https:\\\/\\\/chs-ca.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/chs-ca.org\\\/es\\\/chs-blog\\\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/chs-ca.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/ryan-franco-XECZHb6NoFo-unsplash-scaled.jpg\",\"keywords\":[\"Child Care Provider Resources\",\"Ingl\u00e9s\",\"Recursos para familias\",\"Recursos para Proveedores de Cuidado Infantil\",\"Salud mental\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chs-ca.org\\\/es\\\/chs-blog\\\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\\\/\",\"url\":\"https:\\\/\\\/chs-ca.org\\\/es\\\/chs-blog\\\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\\\/\",\"name\":\"Ago 2022 - El comportamiento como comunicaci\u00f3n: C\u00f3mo entender las crisis y las rabietas - Children&#039;s Home Society of California\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chs-ca.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/chs-ca.org\\\/es\\\/chs-blog\\\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/chs-ca.org\\\/es\\\/chs-blog\\\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/chs-ca.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/ryan-franco-XECZHb6NoFo-unsplash-scaled.jpg\",\"datePublished\":\"2022-08-09T17:05:54+00:00\",\"dateModified\":\"2023-06-14T17:38:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chs-ca.org\\\/es\\\/chs-blog\\\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/chs-ca.org\\\/es\\\/chs-blog\\\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/chs-ca.org\\\/es\\\/chs-blog\\\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/chs-ca.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/ryan-franco-XECZHb6NoFo-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/chs-ca.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/ryan-franco-XECZHb6NoFo-unsplash-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"A grumpy baby sitting on a picnic blanket.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chs-ca.org\\\/es\\\/chs-blog\\\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/chs-ca.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ago 2022 &#8211; El comportamiento como comunicaci\u00f3n: C\u00f3mo entender las crisis y las rabietas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chs-ca.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/chs-ca.org\\\/es\\\/\",\"name\":\"Children&#039;s Home Society of California\",\"description\":\"We make child care accessible\",\"publisher\":{\"@id\":\"https:\\\/\\\/chs-ca.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/chs-ca.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/chs-ca.org\\\/es\\\/#organization\",\"name\":\"Children's Home Society of California\",\"url\":\"https:\\\/\\\/chs-ca.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/chs-ca.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/chs-ca.org\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/CHS-logo.svg\",\"contentUrl\":\"https:\\\/\\\/chs-ca.org\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/CHS-logo.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Children's Home Society of California\"},\"image\":{\"@id\":\"https:\\\/\\\/chs-ca.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/chs-ca.org\\\/es\\\/#\\\/schema\\\/person\\\/41af37a0daa9fc962be2179a4207fed6\",\"name\":\"Joanna Carlos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/537227568ba03f2d7fd944b3d35545e57623fdfb52dae8cd283cc419a316294b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/537227568ba03f2d7fd944b3d35545e57623fdfb52dae8cd283cc419a316294b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/537227568ba03f2d7fd944b3d35545e57623fdfb52dae8cd283cc419a316294b?s=96&d=mm&r=g\",\"caption\":\"Joanna Carlos\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ago 2022 - El comportamiento como comunicaci\u00f3n: C\u00f3mo entender las crisis y las rabietas - Children&#039;s Home Society of California","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chs-ca.org\/es\/chs-blog\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\/","og_locale":"es_ES","og_type":"article","og_title":"Ago 2022 - El comportamiento como comunicaci\u00f3n: C\u00f3mo entender las crisis y las rabietas","og_description":"Las rabietas y las crisis se suelen utilizar indistintamente para describir un comportamiento caracterizado","og_url":"https:\/\/chs-ca.org\/es\/chs-blog\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\/","og_site_name":"Children&#039;s Home Society of California","article_published_time":"2022-08-09T17:05:54+00:00","article_modified_time":"2023-06-14T17:38:23+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/chs-ca.org\/wp-content\/uploads\/2022\/08\/ryan-franco-XECZHb6NoFo-unsplash-scaled.jpg","type":"image\/jpeg"}],"author":"Joanna Carlos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Joanna Carlos","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/chs-ca.org\/es\/chs-blog\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\/#article","isPartOf":{"@id":"https:\/\/chs-ca.org\/es\/chs-blog\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\/"},"author":{"name":"Joanna Carlos","@id":"https:\/\/chs-ca.org\/es\/#\/schema\/person\/41af37a0daa9fc962be2179a4207fed6"},"headline":"Ago 2022 &#8211; El comportamiento como comunicaci\u00f3n: C\u00f3mo entender las crisis y las rabietas","datePublished":"2022-08-09T17:05:54+00:00","dateModified":"2023-06-14T17:38:23+00:00","mainEntityOfPage":{"@id":"https:\/\/chs-ca.org\/es\/chs-blog\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\/"},"wordCount":1241,"publisher":{"@id":"https:\/\/chs-ca.org\/es\/#organization"},"image":{"@id":"https:\/\/chs-ca.org\/es\/chs-blog\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\/#primaryimage"},"thumbnailUrl":"https:\/\/chs-ca.org\/wp-content\/uploads\/2022\/08\/ryan-franco-XECZHb6NoFo-unsplash-scaled.jpg","keywords":["Child Care Provider Resources","Ingl\u00e9s","Recursos para familias","Recursos para Proveedores de Cuidado Infantil","Salud mental"],"articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/chs-ca.org\/es\/chs-blog\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\/","url":"https:\/\/chs-ca.org\/es\/chs-blog\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\/","name":"Ago 2022 - El comportamiento como comunicaci\u00f3n: C\u00f3mo entender las crisis y las rabietas - Children&#039;s Home Society of California","isPartOf":{"@id":"https:\/\/chs-ca.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/chs-ca.org\/es\/chs-blog\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\/#primaryimage"},"image":{"@id":"https:\/\/chs-ca.org\/es\/chs-blog\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\/#primaryimage"},"thumbnailUrl":"https:\/\/chs-ca.org\/wp-content\/uploads\/2022\/08\/ryan-franco-XECZHb6NoFo-unsplash-scaled.jpg","datePublished":"2022-08-09T17:05:54+00:00","dateModified":"2023-06-14T17:38:23+00:00","breadcrumb":{"@id":"https:\/\/chs-ca.org\/es\/chs-blog\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chs-ca.org\/es\/chs-blog\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/chs-ca.org\/es\/chs-blog\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\/#primaryimage","url":"https:\/\/chs-ca.org\/wp-content\/uploads\/2022\/08\/ryan-franco-XECZHb6NoFo-unsplash-scaled.jpg","contentUrl":"https:\/\/chs-ca.org\/wp-content\/uploads\/2022\/08\/ryan-franco-XECZHb6NoFo-unsplash-scaled.jpg","width":2560,"height":1707,"caption":"A grumpy baby sitting on a picnic blanket."},{"@type":"BreadcrumbList","@id":"https:\/\/chs-ca.org\/es\/chs-blog\/ago-2022-el-comportamiento-como-comunicacion-como-entender-las-crisis-y-las-rabietas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/chs-ca.org\/es\/"},{"@type":"ListItem","position":2,"name":"Ago 2022 &#8211; El comportamiento como comunicaci\u00f3n: C\u00f3mo entender las crisis y las rabietas"}]},{"@type":"WebSite","@id":"https:\/\/chs-ca.org\/es\/#website","url":"https:\/\/chs-ca.org\/es\/","name":"Children&#039;s Home Society of California","description":"We make child care accessible","publisher":{"@id":"https:\/\/chs-ca.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chs-ca.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/chs-ca.org\/es\/#organization","name":"Children's Home Society of California","url":"https:\/\/chs-ca.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/chs-ca.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/chs-ca.org\/wp-content\/uploads\/2021\/09\/CHS-logo.svg","contentUrl":"https:\/\/chs-ca.org\/wp-content\/uploads\/2021\/09\/CHS-logo.svg","width":"1024","height":"1024","caption":"Children's Home Society of California"},"image":{"@id":"https:\/\/chs-ca.org\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/chs-ca.org\/es\/#\/schema\/person\/41af37a0daa9fc962be2179a4207fed6","name":"Joanna Carlos","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/537227568ba03f2d7fd944b3d35545e57623fdfb52dae8cd283cc419a316294b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/537227568ba03f2d7fd944b3d35545e57623fdfb52dae8cd283cc419a316294b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/537227568ba03f2d7fd944b3d35545e57623fdfb52dae8cd283cc419a316294b?s=96&d=mm&r=g","caption":"Joanna Carlos"}}]}},"_links":{"self":[{"href":"https:\/\/chs-ca.org\/es\/wp-json\/wp\/v2\/posts\/9501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chs-ca.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chs-ca.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chs-ca.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/chs-ca.org\/es\/wp-json\/wp\/v2\/comments?post=9501"}],"version-history":[{"count":0,"href":"https:\/\/chs-ca.org\/es\/wp-json\/wp\/v2\/posts\/9501\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chs-ca.org\/es\/wp-json\/wp\/v2\/media\/8563"}],"wp:attachment":[{"href":"https:\/\/chs-ca.org\/es\/wp-json\/wp\/v2\/media?parent=9501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chs-ca.org\/es\/wp-json\/wp\/v2\/categories?post=9501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chs-ca.org\/es\/wp-json\/wp\/v2\/tags?post=9501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}